{"id":4130,"date":"2021-09-08T21:12:19","date_gmt":"2021-09-08T21:12:19","guid":{"rendered":"https:\/\/green-up.ch\/chia-siamo\/"},"modified":"2022-11-08T14:31:06","modified_gmt":"2022-11-08T14:31:06","slug":"chi-siamo","status":"publish","type":"page","link":"https:\/\/green-up.ch\/it\/chi-siamo\/","title":{"rendered":"Chi Siamo"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;||0px||false|false&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row column_structure=&#8221;1_2,1_2&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;0px|0px|0px|0px|false|false&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.16&#8243; text_font_size=&#8221;30px&#8221; text_line_height=&#8221;1.5em&#8221; header_text_color=&#8221;#000000&#8243; header_font_size=&#8221;80px&#8221; header_letter_spacing=&#8221;1px&#8221; z_index=&#8221;1&#8243; custom_margin=&#8221;100px||||false|false&#8221; custom_margin_tablet=&#8221;|||0px&#8221; custom_margin_phone=&#8221;&#8221; custom_margin_last_edited=&#8221;on|phone&#8221; header_font_size_tablet=&#8221;80px&#8221; header_font_size_phone=&#8221;60px&#8221; header_font_size_last_edited=&#8221;on|phone&#8221; header_letter_spacing_tablet=&#8221;0px&#8221; header_letter_spacing_phone=&#8221;&#8221; header_letter_spacing_last_edited=&#8221;on|tablet&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h1 style=\"text-align: right;\"><span style=\"color: #00506e;\">Chi siamo<\/span><\/h1>\n<p class=\"p1\" style=\"text-align: right;\"><em>&#8220;La semplicit\u00e0 \u00e8 l&#8217;ultima sofisticazione.&#8221; <\/em><span style=\"font-size: small;\">Leonardo \u00a0Da Vinci<\/span><\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p style=\"text-align: right;\">GreenUp \u00e8 il (nuovo) nome dell\u2019associazione svizzera senza scopo di lucro \u201cUmwelt Plattform\u201d, che ha le sue radici a Basilea.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_image src=&#8221;https:\/\/green-up.ch\/wp-content\/uploads\/2021\/09\/About.png&#8221; title_text=&#8221;Chi siamo&#8221; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; width=&#8221;87%&#8221; custom_margin=&#8221;||-80px||false|false&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; admin_label=&#8221;Services&#8221; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;0px|||||&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row column_structure=&#8221;3_5,2_5&#8243; _builder_version=&#8221;4.16&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;3_5&#8243; _builder_version=&#8221;4.16&#8243; z_index=&#8221;10&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_image src=&#8221;https:\/\/green-up.ch\/wp-content\/uploads\/2021\/06\/about_duotone.jpg&#8221; title_text=&#8221;about_duotone&#8221; _builder_version=&#8221;4.16&#8243; custom_margin=&#8221;|||-15vw|false|false&#8221; custom_margin_tablet=&#8221;|||0vw|false|false&#8221; custom_margin_phone=&#8221;&#8221; custom_margin_last_edited=&#8221;on|desktop&#8221; border_radii=&#8221;on|30px|30px|30px|30px&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][et_pb_video src=&#8221;https:\/\/youtu.be\/mTxqfCmRErI&#8221; play_icon_color=&#8221;#87F5B4&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; border_radii=&#8221;on|30px|30px|30px|30px&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_video][\/et_pb_column][et_pb_column type=&#8221;2_5&#8243; _builder_version=&#8221;4.16&#8243; z_index=&#8221;50&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.16&#8243; text_font=&#8221;||||||||&#8221; text_font_size=&#8221;16px&#8221; text_line_height=&#8221;1.8em&#8221; header_2_font=&#8221;Prompt|200|||||||&#8221; header_2_text_color=&#8221;#000000&#8243; header_2_font_size=&#8221;60px&#8221; header_2_line_height=&#8221;1.2em&#8221; header_4_font=&#8221;Prompt|600||on|||||&#8221; header_4_text_color=&#8221;#ff6f7e&#8221; header_4_font_size=&#8221;12px&#8221; header_4_letter_spacing=&#8221;2px&#8221; header_4_line_height=&#8221;1.2em&#8221; z_index=&#8221;1&#8243; custom_margin=&#8221;54px||0px||false|false&#8221; text_font_size_tablet=&#8221;&#8221; text_font_size_phone=&#8221;14px&#8221; text_font_size_last_edited=&#8221;on|desktop&#8221; header_2_font_size_tablet=&#8221;60px&#8221; header_2_font_size_phone=&#8221;30px&#8221; header_2_font_size_last_edited=&#8221;on|phone&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>Siamo attivi a lovello nazionale grazie ad un network che connette 6 citt\u00e0: Basilea, Davos, La Chaud-De-Fonds, Zurigo e, da settembre 2021, anche Lugano e Sion.<\/p>\n<p>GreenUp \u00e8 nata in risposta ad una sfida lanciata dalla Umweltallianz. Da quel momento, usiamo il nostro spirito positivo e creativo per ispirare le persone ad agire in modo pi\u00f9 sostenibile e adottare uno stile di vita pi\u00f9 leggero, usando meno risorse sia a casa che al lavoro. Lo facciamo per il bene del pianeta, ma anche per vivere pi\u00f9 leggeri, connessi e felici. Cerchiamo di raggiungere questi obiettivi tramite eventi e progetti innovativi.\u00a0<\/p>\n<p>Realizziamo ci\u00f2 tramite un team piccolo ed innovativo di giovani professionisti che lavorano a tempo parziale, una comunit\u00e0 eccezionale di circa 50 volontari e una fantastica direzione. Siamo finanziati da coloro che condividono la nostra passione e punti di vista.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; admin_label=&#8221;About&#8221; _builder_version=&#8221;4.16&#8243; background_color=&#8221;#E6FFEB&#8221; bottom_divider_color=&#8221;RGBA(0,0,0,0)&#8221; bottom_divider_height=&#8221;10vw&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;||0px|||&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.16&#8243; header_2_font=&#8221;Prompt|200|||||||&#8221; header_2_font_size=&#8221;60px&#8221; header_2_line_height=&#8221;1.2em&#8221; header_4_font=&#8221;Prompt|600||on|||||&#8221; header_4_font_size=&#8221;14px&#8221; header_4_letter_spacing=&#8221;2px&#8221; header_4_line_height=&#8221;1.2em&#8221; z_index=&#8221;1&#8243; text_orientation=&#8221;center&#8221; max_width=&#8221;800px&#8221; module_alignment=&#8221;center&#8221; header_2_font_size_tablet=&#8221;40px&#8221; header_2_font_size_phone=&#8221;25px&#8221; header_2_font_size_last_edited=&#8221;on|phone&#8221; text_orientation_tablet=&#8221;left&#8221; text_orientation_phone=&#8221;&#8221; text_orientation_last_edited=&#8221;on|desktop&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h1 style=\"text-align: center;\">La nostra storia e impatto<\/h1>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_4,1_4,1_4,1_4&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;25px|||||&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;4.16&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.16&#8243; text_font=&#8221;||||||||&#8221; text_font_size=&#8221;16px&#8221; text_line_height=&#8221;1.8em&#8221; custom_margin=&#8221;|-173px||||&#8221; text_font_size_tablet=&#8221;&#8221; text_font_size_phone=&#8221;14px&#8221; text_font_size_last_edited=&#8221;on|desktop&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<div class=\"et_pb_column et_pb_column_1_4 et_pb_column_5  et_pb_css_mix_blend_mode_passthrough\">\n<div class=\"et_pb_module et_pb_text et_pb_text_4  et_pb_text_align_left et_pb_bg_layout_light\">\n<div class=\"et_pb_text_inner\">\n<p>GreenUp \u00e8 nata nel 2016 dal un progetto di Umweltallianz, differenziandosi nell\u2019approcio verso i bisogni della popolazione svizzera e del pianeta. Se il 25% delle persone \u00e8 disposta a cambiare, possiamo mettere in moto una transizione. Perci\u00f2, adottiamo un approccio positivo e attivo, per spingere pi\u00f9 persone possibile ad agire e cambiare il loro stile di vita.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;4.16&#8243; global_colors_info=&#8221;{}&#8221;][\/et_pb_column][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.16&#8243; text_font=&#8221;||||||||&#8221; text_font_size=&#8221;16px&#8221; text_line_height=&#8221;1.8em&#8221; custom_margin=&#8221;|-156px||||&#8221; text_font_size_tablet=&#8221;&#8221; text_font_size_phone=&#8221;14px&#8221; text_font_size_last_edited=&#8221;on|desktop&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>Grazie al nostro lavoro, 5\u2019000 persone hanno agito in favore di uno stile di vita pi\u00f9 sostenibile, imparando come vivere in modo pi\u00f9 semplice. Grazie alle campagne, ai nostri progetti e ai social media abbiamo contribuito a rafforzare la cosapevolezza di circa 100\u2019000 persone, mostrando che \u201cmeno \u00e8 meglio\u201d.\u00a0<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;4.16&#8243; global_colors_info=&#8221;{}&#8221;][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row column_structure=&#8221;1_2,1_2&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;RGBA(0,0,0,0)&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;RGBA(0,0,0,0)&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h1>Missione<\/h1>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>Con il motto \u201cmeno \u00e8 meglio\u201d crediamo che ognuno di noi possa vivere in modo pi\u00f9 semplice e felice. Grazie ai nostri eventi, ai progetti e alle risorse online proponiamo delle esperienze positive per una vita pi\u00f9 \u201cverde\u201d.<\/p>\n<p>[\/et_pb_text][et_pb_button button_url=&#8221;https:\/\/green-up.ch\/it\/progetti\/&#8221; button_text=&#8221;Fai un progetto con noi. &#8221; button_alignment=&#8221;left&#8221; _builder_version=&#8221;4.16&#8243; custom_button=&#8221;on&#8221; button_text_size=&#8221;14px&#8221; button_text_color=&#8221;#00506E&#8221; button_bg_color=&#8221;#87F5B4&#8243; button_border_width=&#8221;0px&#8221; button_border_radius=&#8221;30px&#8221; button_letter_spacing=&#8221;2px&#8221; button_font=&#8221;|||on|||||&#8221; button_use_icon=&#8221;off&#8221; transform_translate=&#8221;0px|100%&#8221; transform_translate_linked=&#8221;off&#8221; z_index=&#8221;1&#8243; custom_margin=&#8221;||0px||false|false&#8221; custom_padding=&#8221;15px|30px|15px|30px|true|true&#8221; button_bg_color_last_edited=&#8221;off|desktop&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221; button_bg_color__hover_enabled=&#8221;on|hover&#8221; button_bg_color__hover=&#8221;#E6FFEB&#8221; button_bg_enable_color__hover=&#8221;on&#8221; button_text_color__hover=&#8221;#ffffff&#8221; button_border_color__hover=&#8221;rgba(0,0,0,0)&#8221;][\/et_pb_button][\/et_pb_column][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_image src=&#8221;https:\/\/green-up.ch\/wp-content\/uploads\/2021\/05\/schema-1.png&#8221; title_text=&#8221;schema&#8221; align_tablet=&#8221;center&#8221; align_phone=&#8221;&#8221; align_last_edited=&#8221;on|phone&#8221; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; width=&#8221;80%&#8221; custom_margin=&#8221;||||false|false&#8221; custom_margin_tablet=&#8221;&#8221; custom_margin_phone=&#8221;70px||||false|false&#8221; custom_margin_last_edited=&#8221;on|desktop&#8221; border_radii=&#8221;on|30px|30px|30px|30px&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#E6FFEB&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row _builder_version=&#8221;4.16&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.16&#8243; header_2_font=&#8221;||||||||&#8221; header_2_text_color=&#8221;#00506E&#8221; header_2_font_size=&#8221;60px&#8221; header_2_line_height=&#8221;1.2em&#8221; header_4_font=&#8221;Prompt|600||on|||||&#8221; header_4_font_size=&#8221;14px&#8221; header_4_letter_spacing=&#8221;2px&#8221; header_4_line_height=&#8221;1.2em&#8221; z_index=&#8221;1&#8243; text_orientation=&#8221;center&#8221; max_width=&#8221;800px&#8221; module_alignment=&#8221;center&#8221; header_2_font_size_tablet=&#8221;40px&#8221; header_2_font_size_phone=&#8221;25px&#8221; header_2_font_size_last_edited=&#8221;on|phone&#8221; text_orientation_tablet=&#8221;left&#8221; text_orientation_phone=&#8221;&#8221; text_orientation_last_edited=&#8221;on|desktop&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h2>I nostri valori<\/h2>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_4,1_4,1_4,1_4&#8243; use_custom_gutter=&#8221;on&#8221; gutter_width=&#8221;2&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; link_option_url=&#8221;#&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_blurb title=&#8221;Indipendenza&#8221; url=&#8221;#&#8221; image=&#8221;https:\/\/green-up.ch\/wp-content\/uploads\/2021\/05\/goutte.png&#8221; image_icon_width=&#8221;50%&#8221; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;3e17696c-80b2-42c8-b2b5-9d31146ea833&#8243; header_font_size=&#8221;35px&#8221; module_alignment=&#8221;center&#8221; image_max_width=&#8221;50%&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221; background_color__hover=&#8221;#87F5B4&#8243;]<\/p>\n<p class=\"p1\" style=\"text-align: left;\">Siamo a disposizione di tutti\/e, senza discriminazione di alcun tipo, che sia essa di genere, religiosa, politica, o altro. Lavoriamo con qualsiasi persona o ente, fintanto che vi siano degli obiettivi comuni.\u00a0<\/p>\n<p>[\/et_pb_blurb][\/et_pb_column][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; link_option_url=&#8221;#&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_blurb title=&#8221;Collaborativo&#8221; url=&#8221;#&#8221; image=&#8221;https:\/\/green-up.ch\/wp-content\/uploads\/2021\/05\/cible.png&#8221; image_icon_width=&#8221;50%&#8221; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;3e17696c-80b2-42c8-b2b5-9d31146ea833&#8243; header_font_size=&#8221;35px&#8221; module_alignment=&#8221;center&#8221; image_max_width=&#8221;50%&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221; background_color__hover=&#8221;#87F5B4&#8243;]<\/p>\n<p class=\"p1\" style=\"text-align: left;\">Collaborazione: incoraggiamo la collaborazione e siamo sempre alla ricerca di partner. Condividiamo con piacere la nostra conoscenza ed esperienza.<\/p>\n<p>[\/et_pb_blurb][\/et_pb_column][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; link_option_url=&#8221;#&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_blurb title=&#8221;Positivit\u00e0&#8221; url=&#8221;#&#8221; image=&#8221;https:\/\/green-up.ch\/wp-content\/uploads\/2021\/05\/fleur.png&#8221; image_icon_width=&#8221;50%&#8221; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;3e17696c-80b2-42c8-b2b5-9d31146ea833&#8243; header_font_size=&#8221;35px&#8221; module_alignment=&#8221;center&#8221; image_max_width=&#8221;50%&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221; background_color__hover=&#8221;#87F5B4&#8243;]<\/p>\n<p class=\"p1\" style=\"text-align: left;\">Siamo una comunit\u00e0 di persone attive, che credono che si, tutto \u00e8 possibile. Comunichiamo sempre in modo propositivo.<\/p>\n<p>[\/et_pb_blurb][\/et_pb_column][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; link_option_url=&#8221;#&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_blurb title=&#8221;Apprendimento&#8221; url=&#8221;#&#8221; image=&#8221;https:\/\/green-up.ch\/wp-content\/uploads\/2021\/05\/arbre.png&#8221; image_icon_width=&#8221;50%&#8221; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;3e17696c-80b2-42c8-b2b5-9d31146ea833&#8243; header_font_size=&#8221;35px&#8221; module_alignment=&#8221;center&#8221; image_max_width=&#8221;50%&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221; background_color__hover=&#8221;#87F5B4&#8243;]<\/p>\n<p class=\"p1\" style=\"text-align: left;\">Ci piace il concetto di \u201cimparare facendo\u201d. Esploriamo metodi nuovi e alternativi. Anche se a volte non funziona, provare ci rende pi\u00f9 forti.<\/p>\n<p>[\/et_pb_blurb][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#87F5B4&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_row _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; max_width=&#8221;50em&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h1><span style=\"color: #008c87;\"><span style=\"color: #00506e;\">Rapporti annuali &amp; finanziari<\/span><br \/><\/span><\/h1>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_3,1_3,1_3&#8243; _builder_version=&#8221;4.18.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; max_width=&#8221;50em&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p><span style=\"color: #008c87;\">Per saperne di pi\u00f9 sull&#8217;organizzazione e sui dati finanziari, consultate i nostri rapporti:<\/span><\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_button button_url=&#8221;https:\/\/green-up.ch\/wp-content\/uploads\/2021\/09\/UP-Annual-Report-2019.pdf&#8221; url_new_window=&#8221;on&#8221; button_text=&#8221;Rapporto Annuale 2019 (en)&#8221; button_alignment=&#8221;left&#8221; _builder_version=&#8221;4.18.1&#8243; custom_button=&#8221;on&#8221; button_text_size=&#8221;14px&#8221; button_text_color=&#8221;#FFFFFF&#8221; button_bg_color=&#8221;#00506E&#8221; button_border_width=&#8221;0px&#8221; button_border_radius=&#8221;30px&#8221; button_letter_spacing=&#8221;2px&#8221; button_font=&#8221;|||on|||||&#8221; button_use_icon=&#8221;off&#8221; transform_translate=&#8221;0px|0%&#8221; transform_translate_linked=&#8221;off&#8221; z_index=&#8221;1&#8243; custom_margin=&#8221;15px|15px|15px|15px|false|false&#8221; custom_padding=&#8221;15px|30px|15px|30px|true|true&#8221; button_bg_color_last_edited=&#8221;off|desktop&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221; button_bg_color__hover_enabled=&#8221;on|hover&#8221; button_bg_color__hover=&#8221;#E6FFEB&#8221; button_bg_enable_color__hover=&#8221;on&#8221; button_text_color__hover=&#8221;#ffffff&#8221; button_border_color__hover=&#8221;rgba(0,0,0,0)&#8221;][\/et_pb_button][et_pb_button button_alignment=&#8221;left&#8221; _builder_version=&#8221;4.18.0&#8243; custom_button=&#8221;on&#8221; button_text_size=&#8221;14px&#8221; button_text_color=&#8221;#FFFFFF&#8221; button_bg_color=&#8221;#00506E&#8221; button_border_width=&#8221;0px&#8221; button_border_radius=&#8221;30px&#8221; button_letter_spacing=&#8221;2px&#8221; button_font=&#8221;|||on|||||&#8221; button_use_icon=&#8221;off&#8221; transform_translate=&#8221;0px|0%&#8221; transform_translate_linked=&#8221;off&#8221; z_index=&#8221;1&#8243; custom_margin=&#8221;||0px||false|false&#8221; custom_padding=&#8221;15px|30px|15px|30px|true|true&#8221; button_bg_color_last_edited=&#8221;off|desktop&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221; button_bg_color__hover_enabled=&#8221;on|hover&#8221; button_bg_color__hover=&#8221;#E6FFEB&#8221; button_bg_enable_color__hover=&#8221;on&#8221; button_text_color__hover=&#8221;#ffffff&#8221; button_border_color__hover=&#8221;rgba(0,0,0,0)&#8221;][\/et_pb_button][et_pb_button button_url=&#8221;https:\/\/green-up.ch\/wp-content\/uploads\/2021\/09\/UP_Annual_Report_2020_en.pdf&#8221; url_new_window=&#8221;on&#8221; button_text=&#8221;Rapporto Annuale 2020 (en)&#8221; button_alignment=&#8221;left&#8221; _builder_version=&#8221;4.18.1&#8243; custom_button=&#8221;on&#8221; button_text_size=&#8221;14px&#8221; button_text_color=&#8221;#FFFFFF&#8221; button_bg_color=&#8221;#00506E&#8221; button_border_width=&#8221;0px&#8221; button_border_radius=&#8221;30px&#8221; button_letter_spacing=&#8221;2px&#8221; button_font=&#8221;|||on|||||&#8221; button_use_icon=&#8221;off&#8221; transform_translate=&#8221;0px|0%&#8221; transform_translate_linked=&#8221;off&#8221; z_index=&#8221;1&#8243; custom_margin=&#8221;15px|15px|15px|15px|false|false&#8221; custom_padding=&#8221;15px|30px|15px|30px|true|true&#8221; button_bg_color_last_edited=&#8221;off|desktop&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221; button_bg_color__hover_enabled=&#8221;on|hover&#8221; button_bg_color__hover=&#8221;#E6FFEB&#8221; button_bg_enable_color__hover=&#8221;on&#8221; button_text_color__hover=&#8221;#ffffff&#8221; button_border_color__hover=&#8221;rgba(0,0,0,0)&#8221;][\/et_pb_button][et_pb_button button_url=&#8221;@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoicG9zdF9saW5rX3VybF9hdHRhY2htZW50Iiwic2V0dGluZ3MiOnsicG9zdF9pZCI6Ijk4MTYifX0=@&#8221; url_new_window=&#8221;on&#8221; button_text=&#8221;Rapporto Annuale 2021&#8243; button_alignment=&#8221;left&#8221; _builder_version=&#8221;4.18.1&#8243; _dynamic_attributes=&#8221;button_url&#8221; custom_button=&#8221;on&#8221; button_text_size=&#8221;14px&#8221; button_text_color=&#8221;#FFFFFF&#8221; button_bg_color=&#8221;#00506E&#8221; button_border_width=&#8221;0px&#8221; button_border_radius=&#8221;30px&#8221; button_letter_spacing=&#8221;2px&#8221; button_font=&#8221;|||on|||||&#8221; button_use_icon=&#8221;off&#8221; transform_translate=&#8221;0px|0%&#8221; transform_translate_linked=&#8221;off&#8221; z_index=&#8221;1&#8243; custom_margin=&#8221;15px|15px|15px|15px|false|false&#8221; custom_padding=&#8221;15px|30px|15px|30px|true|true&#8221; hover_enabled=&#8221;0&#8243; button_bg_color_last_edited=&#8221;off|desktop&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221; button_bg_color__hover_enabled=&#8221;on|hover&#8221; button_bg_color__hover=&#8221;#E6FFEB&#8221; button_bg_enable_color__hover=&#8221;on&#8221; button_text_color__hover=&#8221;#ffffff&#8221; button_border_color__hover=&#8221;rgba(0,0,0,0)&#8221; sticky_enabled=&#8221;0&#8243;][\/et_pb_button][\/et_pb_column][et_pb_column type=&#8221;1_3&#8243; _builder_version=&#8221;4.18.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_button button_url=&#8221;@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoicG9zdF9saW5rX3VybF9hdHRhY2htZW50Iiwic2V0dGluZ3MiOnsicG9zdF9pZCI6Ijk0ODgifX0=@&#8221; url_new_window=&#8221;on&#8221; button_text=&#8221;Rapporto Finanziario 2020&#8243; button_alignment=&#8221;left&#8221; _builder_version=&#8221;4.18.0&#8243; _dynamic_attributes=&#8221;button_url&#8221; custom_button=&#8221;on&#8221; button_text_size=&#8221;14px&#8221; button_text_color=&#8221;#FFFFFF&#8221; button_bg_color=&#8221;#00506E&#8221; button_border_width=&#8221;0px&#8221; button_border_radius=&#8221;30px&#8221; button_letter_spacing=&#8221;2px&#8221; button_font=&#8221;|||on|||||&#8221; button_use_icon=&#8221;off&#8221; transform_translate=&#8221;0px|0%&#8221; transform_translate_linked=&#8221;off&#8221; z_index=&#8221;1&#8243; custom_margin=&#8221;15px|15px|15px|15px|false|false&#8221; custom_padding=&#8221;15px|30px|15px|30px|true|true&#8221; button_bg_color_last_edited=&#8221;off|desktop&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221; button_bg_color__hover_enabled=&#8221;on|hover&#8221; button_bg_color__hover=&#8221;#E6FFEB&#8221; button_bg_enable_color__hover=&#8221;on&#8221; button_text_color__hover=&#8221;#ffffff&#8221; button_border_color__hover=&#8221;rgba(0,0,0,0)&#8221;][\/et_pb_button][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#FFFFFF&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h1 style=\"text-align: center;\">Vuoi farne parte?<\/h1>\n<p>[\/et_pb_text][et_pb_button button_url=&#8221;https:\/\/green-up.ch\/it\/unisciti-a-noi\/&#8221; url_new_window=&#8221;on&#8221; button_text=&#8221;Unisciti a noi!&#8221; button_alignment=&#8221;center&#8221; _builder_version=&#8221;4.18.0&#8243; custom_button=&#8221;on&#8221; button_text_size=&#8221;14px&#8221; button_text_color=&#8221;#00506E&#8221; button_bg_color=&#8221;#87F5B4&#8243; button_border_width=&#8221;0px&#8221; button_border_radius=&#8221;30px&#8221; button_letter_spacing=&#8221;2px&#8221; button_font=&#8221;|||on|||||&#8221; button_use_icon=&#8221;off&#8221; transform_translate=&#8221;0px|0%&#8221; transform_translate_linked=&#8221;off&#8221; z_index=&#8221;1&#8243; custom_margin=&#8221;||0px||false|false&#8221; custom_padding=&#8221;15px|30px|15px|30px|true|true&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221; button_bg_color__hover_enabled=&#8221;on|hover&#8221; button_bg_color__hover=&#8221;#008C87&#8243; button_bg_enable_color__hover=&#8221;on&#8221; button_text_color__hover=&#8221;#ffffff&#8221; button_border_color__hover=&#8221;rgba(0,0,0,0)&#8221;][\/et_pb_button][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; admin_label=&#8221;Footer&#8221; _builder_version=&#8221;4.16&#8243; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row _builder_version=&#8221;4.16&#8243; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.16&#8243; text_font=&#8221;|600|||||||&#8221; text_font_size=&#8221;16px&#8221; text_line_height=&#8221;1.8em&#8221; header_4_font=&#8221;Prompt|600||on|||||&#8221; header_4_font_size=&#8221;14px&#8221; header_4_letter_spacing=&#8221;2px&#8221; header_4_line_height=&#8221;1.2em&#8221; z_index=&#8221;1&#8243; text_orientation=&#8221;center&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h4>SEGUITECI SUI SOCIAL MEDIA.<\/h4>\n<p>[\/et_pb_text][et_pb_social_media_follow _builder_version=&#8221;4.18.0&#8243; text_orientation=&#8221;center&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_social_media_follow_network social_network=&#8221;facebook&#8221; url=&#8221;https:\/\/www.facebook.com\/greenupswitzerland&#8221; icon_color=&#8221;#FFFFFF&#8221; use_icon_font_size=&#8221;on&#8221; icon_font_size=&#8221;15px&#8221; _builder_version=&#8221;4.16&#8243; background_color=&#8221;#87F5B4&#8243; background_enable_color=&#8221;on&#8221; border_radii=&#8221;on|50px|50px|50px|50px&#8221; global_colors_info=&#8221;{}&#8221; follow_button=&#8221;off&#8221; url_new_window=&#8221;on&#8221;]facebook[\/et_pb_social_media_follow_network][et_pb_social_media_follow_network social_network=&#8221;linkedin&#8221; url=&#8221;https:\/\/www.linkedin.com\/company\/greenupswitzerland\/&#8221; icon_color=&#8221;#FFFFFF&#8221; use_icon_font_size=&#8221;on&#8221; icon_font_size=&#8221;15px&#8221; _builder_version=&#8221;4.18.0&#8243; background_color=&#8221;#87F5B4&#8243; background_enable_color=&#8221;on&#8221; border_radii=&#8221;on|50px|50px|50px|50px&#8221; global_colors_info=&#8221;{}&#8221; follow_button=&#8221;off&#8221; url_new_window=&#8221;on&#8221;]linkedin[\/et_pb_social_media_follow_network][et_pb_social_media_follow_network social_network=&#8221;instagram&#8221; url=&#8221;https:\/\/www.instagram.com\/greenup.ch\/&#8221; icon_color=&#8221;#FFFFFF&#8221; use_icon_font_size=&#8221;on&#8221; icon_font_size=&#8221;15px&#8221; _builder_version=&#8221;4.16&#8243; background_color=&#8221;#87F5B4&#8243; background_enable_color=&#8221;on&#8221; border_radii=&#8221;on|50px|50px|50px|50px&#8221; global_colors_info=&#8221;{}&#8221; follow_button=&#8221;off&#8221; url_new_window=&#8221;on&#8221;]instagram[\/et_pb_social_media_follow_network][\/et_pb_social_media_follow][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Chi siamo &#8220;La semplicit\u00e0 \u00e8 l&#8217;ultima sofisticazione.&#8221; Leonardo \u00a0Da VinciGreenUp \u00e8 il (nuovo) nome dell\u2019associazione svizzera senza scopo di lucro \u201cUmwelt Plattform\u201d, che ha le sue radici a Basilea.Siamo attivi [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"class_list":["post-4130","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Chi Siamo | Green Up<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/green-up.ch\/it\/chi-siamo\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Chi Siamo | Green Up\" \/>\n<meta property=\"og:description\" content=\"Chi siamo &quot;La semplicit\u00e0 \u00e8 l&#039;ultima sofisticazione.&quot; Leonardo \u00a0Da VinciGreenUp \u00e8 il (nuovo) nome dell\u2019associazione svizzera senza scopo di lucro \u201cUmwelt Plattform\u201d, che ha le sue radici a Basilea.Siamo attivi [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/green-up.ch\/it\/chi-siamo\/\" \/>\n<meta property=\"og:site_name\" content=\"Green Up\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/m.facebook.com\/greenupswitzerland\" \/>\n<meta property=\"article:modified_time\" content=\"2022-11-08T14:31:06+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"16 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/green-up.ch\\\/it\\\/chi-siamo\\\/\",\"url\":\"https:\\\/\\\/green-up.ch\\\/it\\\/chi-siamo\\\/\",\"name\":\"Chi Siamo | Green Up\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/green-up.ch\\\/#website\"},\"datePublished\":\"2021-09-08T21:12:19+00:00\",\"dateModified\":\"2022-11-08T14:31:06+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/green-up.ch\\\/it\\\/chi-siamo\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/green-up.ch\\\/it\\\/chi-siamo\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/green-up.ch\\\/it\\\/chi-siamo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/green-up.ch\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Chi Siamo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/green-up.ch\\\/#website\",\"url\":\"https:\\\/\\\/green-up.ch\\\/\",\"name\":\"GreenUp\",\"description\":\"Inspire, collaborate, empower.\",\"publisher\":{\"@id\":\"https:\\\/\\\/green-up.ch\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/green-up.ch\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/green-up.ch\\\/#organization\",\"name\":\"GreeUp\",\"url\":\"https:\\\/\\\/green-up.ch\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/green-up.ch\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/green-up.ch\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/greenuplogo_rond.png\",\"contentUrl\":\"https:\\\/\\\/green-up.ch\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/greenuplogo_rond.png\",\"width\":600,\"height\":595,\"caption\":\"GreeUp\"},\"image\":{\"@id\":\"https:\\\/\\\/green-up.ch\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/m.facebook.com\\\/greenupswitzerland\",\"https:\\\/\\\/www.instagram.com\\\/greenup.ch\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/greenupswitzerland\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Chi Siamo | Green Up","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/green-up.ch\/it\/chi-siamo\/","og_locale":"it_IT","og_type":"article","og_title":"Chi Siamo | Green Up","og_description":"Chi siamo \"La semplicit\u00e0 \u00e8 l'ultima sofisticazione.\" Leonardo \u00a0Da VinciGreenUp \u00e8 il (nuovo) nome dell\u2019associazione svizzera senza scopo di lucro \u201cUmwelt Plattform\u201d, che ha le sue radici a Basilea.Siamo attivi [&hellip;]","og_url":"https:\/\/green-up.ch\/it\/chi-siamo\/","og_site_name":"Green Up","article_publisher":"https:\/\/m.facebook.com\/greenupswitzerland","article_modified_time":"2022-11-08T14:31:06+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"16 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/green-up.ch\/it\/chi-siamo\/","url":"https:\/\/green-up.ch\/it\/chi-siamo\/","name":"Chi Siamo | Green Up","isPartOf":{"@id":"https:\/\/green-up.ch\/#website"},"datePublished":"2021-09-08T21:12:19+00:00","dateModified":"2022-11-08T14:31:06+00:00","breadcrumb":{"@id":"https:\/\/green-up.ch\/it\/chi-siamo\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/green-up.ch\/it\/chi-siamo\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/green-up.ch\/it\/chi-siamo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/green-up.ch\/"},{"@type":"ListItem","position":2,"name":"Chi Siamo"}]},{"@type":"WebSite","@id":"https:\/\/green-up.ch\/#website","url":"https:\/\/green-up.ch\/","name":"GreenUp","description":"Inspire, collaborate, empower.","publisher":{"@id":"https:\/\/green-up.ch\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/green-up.ch\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/green-up.ch\/#organization","name":"GreeUp","url":"https:\/\/green-up.ch\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/green-up.ch\/#\/schema\/logo\/image\/","url":"https:\/\/green-up.ch\/wp-content\/uploads\/2021\/11\/greenuplogo_rond.png","contentUrl":"https:\/\/green-up.ch\/wp-content\/uploads\/2021\/11\/greenuplogo_rond.png","width":600,"height":595,"caption":"GreeUp"},"image":{"@id":"https:\/\/green-up.ch\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/m.facebook.com\/greenupswitzerland","https:\/\/www.instagram.com\/greenup.ch\/","https:\/\/www.linkedin.com\/company\/greenupswitzerland\/"]}]}},"_links":{"self":[{"href":"https:\/\/green-up.ch\/it\/wp-json\/wp\/v2\/pages\/4130","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/green-up.ch\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/green-up.ch\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/green-up.ch\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/green-up.ch\/it\/wp-json\/wp\/v2\/comments?post=4130"}],"version-history":[{"count":42,"href":"https:\/\/green-up.ch\/it\/wp-json\/wp\/v2\/pages\/4130\/revisions"}],"predecessor-version":[{"id":9817,"href":"https:\/\/green-up.ch\/it\/wp-json\/wp\/v2\/pages\/4130\/revisions\/9817"}],"wp:attachment":[{"href":"https:\/\/green-up.ch\/it\/wp-json\/wp\/v2\/media?parent=4130"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}