{"id":4440,"date":"2021-09-10T07:15:44","date_gmt":"2021-09-10T07:15:44","guid":{"rendered":"https:\/\/green-up.ch\/2021\/09\/10\/greenup-inspirer-collaborer-favoriser\/"},"modified":"2021-09-20T11:50:02","modified_gmt":"2021-09-20T11:50:02","slug":"greenup-inspirer-collaborer-favoriser","status":"publish","type":"post","link":"https:\/\/green-up.ch\/fr\/2021\/09\/10\/greenup-inspirer-collaborer-favoriser\/","title":{"rendered":"GreenUp &#8211; inspirer, collaborer, favoriser !"},"content":{"rendered":"\n\n[et_pb_section fb_built=\u00a0\u00bb1&Prime; _builder_version=\u00a0\u00bb3.22&Prime; min_height=\u00a0\u00bb954px\u00a0\u00bb custom_padding=\u00a0\u00bb0px|||||\u00a0\u00bb][et_pb_row _builder_version=\u00a0\u00bb3.25&Prime; background_size=\u00a0\u00bbinitial\u00a0\u00bb background_position=\u00a0\u00bbtop_left\u00a0\u00bb background_repeat=\u00a0\u00bbrepeat\u00a0\u00bb custom_padding=\u00a0\u00bb||0px|||\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb3.25&Prime; custom_padding=\u00a0\u00bb|||\u00a0\u00bb custom_padding__hover=\u00a0\u00bb|||\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb3.27.4&Prime; background_size=\u00a0\u00bbinitial\u00a0\u00bb background_position=\u00a0\u00bbtop_left\u00a0\u00bb background_repeat=\u00a0\u00bbrepeat\u00a0\u00bb]<p>Vous nous connaissez encore sous le nom de \u00ab\u00a0UP\u00a0\u00bb ou Umwelt Platform\u00a0\u00bb ? Pendant la longue p\u00e9riode de Corona, nous y avons r\u00e9fl\u00e9chi. Nous avons r\u00e9alis\u00e9 que ce nom ne nous convenait plus. Nous sommes nationaux, nous travaillons en 4 langues, nous sommes dynamiques, positifs et nous voulons rester simples : D\u00e9sormais, nous nous appelons GreenUp et nous apparaissons plus forts, plus verts et plus connect\u00e9s ! Comme tout est devenu un peu plus calme et que nous n&rsquo;\u00e9tions plus autoris\u00e9s \u00e0 organiser des \u00e9v\u00e9nements, vous n&rsquo;avez pas beaucoup entendu parler de nous. Mais avec notre nouvelle apparence, nous changeons cela d\u00e8s maintenant.\u00a0<\/p>\r\n<p>Ces derniers mois, nous avons \u00e9t\u00e9 occup\u00e9s \u00e0 d\u00e9velopper nos activit\u00e9s. Nous sommes tr\u00e8s fiers de pouvoir organiser des \u00e9v\u00e9nements GreenUp \u00e0 Sion et Lugano, ainsi qu&rsquo;\u00e0 B\u00e2le, Zurich, La Chaux-de-Fonds, Soleure, Locarno et Davos. Notre communaut\u00e9 de plus de 50 b\u00e9n\u00e9voles ne cesse de cro\u00eetre. Nous nous effor\u00e7ons chaque jour de motiver le plus grand nombre de personnes possible pour leur faciliter la vie.<\/p>\r\n<p>En plus de nos s\u00e9ries d&rsquo;\u00e9v\u00e9nements populaires, tels que FoodbyFoot, Circular Safari ou Disco Soup, nous avons \u00e9galement des projets plus importants \u00e0 venir. Parcourez notre site web pour en savoir plus. Comme vous le savez peut-\u00eatre d\u00e9j\u00e0, nous nous concentrons sur les six sujets suivants lors de nos \u00e9v\u00e9nements et projets :<\/p>\r\n<ul>\r\n<li><span style=\"font-weight: 400;\">Sobri\u00e9t\u00e9 Heureuse<\/span><\/li>\r\n<li>Alimentation<\/li>\r\n<li>Vert urbain<\/li>\r\n<li>Vivre, construire &amp; \u00e9nergie<\/li>\r\n<li>\u00c9conomie locale et du partage<\/li>\r\n<li>Z\u00e9ro d\u00e9chet &amp; \u00e9conomie circulaire<\/li>\r\n<li>Mobilit\u00e9 &amp; loisirs\u00a0<\/li>\r\n<\/ul>\r\n<p>Gr\u00e2ce \u00e0 la clart\u00e9 de notre nouveau site web, vous pouvez d\u00e9sormais trouver plus rapidement nos ressources, conseils et astuces pour une vie quotidienne plus simple. Vous souhaitez devenir b\u00e9n\u00e9vole et nous aider \u00e0 atteindre nos objectifs ensemble ? Alors inscrivez-vous d\u00e8s maintenant comme b\u00e9n\u00e9vole dans la ville de votre choix !<\/p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]\n\n","protected":false},"excerpt":{"rendered":"<p>Vous nous connaissez encore sous le nom de \u00ab\u00a0UP\u00a0\u00bb ou Umwelt Platform\u00a0\u00bb ? Pendant la longue p\u00e9riode de Corona, nous y avons r\u00e9fl\u00e9chi. Nous avons r\u00e9alis\u00e9 que ce nom ne [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":4880,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[119],"tags":[],"class_list":["post-4440","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-general-fr"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>GreenUp - inspirer, collaborer, favoriser ! | Green Up<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/green-up.ch\/fr\/2021\/09\/10\/greenup-inspirer-collaborer-favoriser\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"GreenUp - inspirer, collaborer, favoriser ! | Green Up\" \/>\n<meta property=\"og:description\" content=\"Vous nous connaissez encore sous le nom de &quot;UP&quot; ou Umwelt Platform&quot; ? Pendant la longue p\u00e9riode de Corona, nous y avons r\u00e9fl\u00e9chi. Nous avons r\u00e9alis\u00e9 que ce nom ne [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/green-up.ch\/fr\/2021\/09\/10\/greenup-inspirer-collaborer-favoriser\/\" \/>\n<meta property=\"og:site_name\" content=\"Green Up\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/m.facebook.com\/greenupswitzerland\" \/>\n<meta property=\"article:published_time\" content=\"2021-09-10T07:15:44+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-09-20T11:50:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/green-up.ch\/wp-content\/uploads\/2021\/09\/3-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"2048\" \/>\n\t<meta property=\"og:image:height\" content=\"1152\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Nicole\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Nicole\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/green-up.ch\\\/fr\\\/2021\\\/09\\\/10\\\/greenup-inspirer-collaborer-favoriser\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/green-up.ch\\\/fr\\\/2021\\\/09\\\/10\\\/greenup-inspirer-collaborer-favoriser\\\/\"},\"author\":{\"name\":\"Nicole\",\"@id\":\"https:\\\/\\\/green-up.ch\\\/#\\\/schema\\\/person\\\/96bc3613ab7b4c304aa334dc4f32ec6f\"},\"headline\":\"GreenUp &#8211; inspirer, collaborer, favoriser !\",\"datePublished\":\"2021-09-10T07:15:44+00:00\",\"dateModified\":\"2021-09-20T11:50:02+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/green-up.ch\\\/fr\\\/2021\\\/09\\\/10\\\/greenup-inspirer-collaborer-favoriser\\\/\"},\"wordCount\":392,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/green-up.ch\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/green-up.ch\\\/fr\\\/2021\\\/09\\\/10\\\/greenup-inspirer-collaborer-favoriser\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/green-up.ch\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/3-1.png\",\"articleSection\":[\"G\u00e9n\u00e9ral\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/green-up.ch\\\/fr\\\/2021\\\/09\\\/10\\\/greenup-inspirer-collaborer-favoriser\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/green-up.ch\\\/fr\\\/2021\\\/09\\\/10\\\/greenup-inspirer-collaborer-favoriser\\\/\",\"url\":\"https:\\\/\\\/green-up.ch\\\/fr\\\/2021\\\/09\\\/10\\\/greenup-inspirer-collaborer-favoriser\\\/\",\"name\":\"GreenUp - inspirer, collaborer, favoriser ! | Green Up\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/green-up.ch\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/green-up.ch\\\/fr\\\/2021\\\/09\\\/10\\\/greenup-inspirer-collaborer-favoriser\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/green-up.ch\\\/fr\\\/2021\\\/09\\\/10\\\/greenup-inspirer-collaborer-favoriser\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/green-up.ch\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/3-1.png\",\"datePublished\":\"2021-09-10T07:15:44+00:00\",\"dateModified\":\"2021-09-20T11:50:02+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/green-up.ch\\\/fr\\\/2021\\\/09\\\/10\\\/greenup-inspirer-collaborer-favoriser\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/green-up.ch\\\/fr\\\/2021\\\/09\\\/10\\\/greenup-inspirer-collaborer-favoriser\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/green-up.ch\\\/fr\\\/2021\\\/09\\\/10\\\/greenup-inspirer-collaborer-favoriser\\\/#primaryimage\",\"url\":\"https:\\\/\\\/green-up.ch\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/3-1.png\",\"contentUrl\":\"https:\\\/\\\/green-up.ch\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/3-1.png\",\"width\":2048,\"height\":1152},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/green-up.ch\\\/fr\\\/2021\\\/09\\\/10\\\/greenup-inspirer-collaborer-favoriser\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/green-up.ch\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"GreenUp &#8211; inspirer, collaborer, favoriser !\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/green-up.ch\\\/#website\",\"url\":\"https:\\\/\\\/green-up.ch\\\/\",\"name\":\"GreenUp\",\"description\":\"Inspire, collaborate, empower.\",\"publisher\":{\"@id\":\"https:\\\/\\\/green-up.ch\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/green-up.ch\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/green-up.ch\\\/#organization\",\"name\":\"GreeUp\",\"url\":\"https:\\\/\\\/green-up.ch\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/green-up.ch\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/green-up.ch\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/greenuplogo_rond.png\",\"contentUrl\":\"https:\\\/\\\/green-up.ch\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/greenuplogo_rond.png\",\"width\":600,\"height\":595,\"caption\":\"GreeUp\"},\"image\":{\"@id\":\"https:\\\/\\\/green-up.ch\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/m.facebook.com\\\/greenupswitzerland\",\"https:\\\/\\\/www.instagram.com\\\/greenup.ch\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/greenupswitzerland\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/green-up.ch\\\/#\\\/schema\\\/person\\\/96bc3613ab7b4c304aa334dc4f32ec6f\",\"name\":\"Nicole\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5557b90d41c7a6762b388c7f6d44095d114d13d304ec05f8c3142ea72c8748dc?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5557b90d41c7a6762b388c7f6d44095d114d13d304ec05f8c3142ea72c8748dc?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5557b90d41c7a6762b388c7f6d44095d114d13d304ec05f8c3142ea72c8748dc?s=96&d=mm&r=g\",\"caption\":\"Nicole\"},\"url\":\"https:\\\/\\\/green-up.ch\\\/fr\\\/author\\\/nicole\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"GreenUp - inspirer, collaborer, favoriser ! | Green Up","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/green-up.ch\/fr\/2021\/09\/10\/greenup-inspirer-collaborer-favoriser\/","og_locale":"fr_FR","og_type":"article","og_title":"GreenUp - inspirer, collaborer, favoriser ! | Green Up","og_description":"Vous nous connaissez encore sous le nom de \"UP\" ou Umwelt Platform\" ? Pendant la longue p\u00e9riode de Corona, nous y avons r\u00e9fl\u00e9chi. Nous avons r\u00e9alis\u00e9 que ce nom ne [&hellip;]","og_url":"https:\/\/green-up.ch\/fr\/2021\/09\/10\/greenup-inspirer-collaborer-favoriser\/","og_site_name":"Green Up","article_publisher":"https:\/\/m.facebook.com\/greenupswitzerland","article_published_time":"2021-09-10T07:15:44+00:00","article_modified_time":"2021-09-20T11:50:02+00:00","og_image":[{"width":2048,"height":1152,"url":"https:\/\/green-up.ch\/wp-content\/uploads\/2021\/09\/3-1.png","type":"image\/png"}],"author":"Nicole","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Nicole","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/green-up.ch\/fr\/2021\/09\/10\/greenup-inspirer-collaborer-favoriser\/#article","isPartOf":{"@id":"https:\/\/green-up.ch\/fr\/2021\/09\/10\/greenup-inspirer-collaborer-favoriser\/"},"author":{"name":"Nicole","@id":"https:\/\/green-up.ch\/#\/schema\/person\/96bc3613ab7b4c304aa334dc4f32ec6f"},"headline":"GreenUp &#8211; inspirer, collaborer, favoriser !","datePublished":"2021-09-10T07:15:44+00:00","dateModified":"2021-09-20T11:50:02+00:00","mainEntityOfPage":{"@id":"https:\/\/green-up.ch\/fr\/2021\/09\/10\/greenup-inspirer-collaborer-favoriser\/"},"wordCount":392,"commentCount":0,"publisher":{"@id":"https:\/\/green-up.ch\/#organization"},"image":{"@id":"https:\/\/green-up.ch\/fr\/2021\/09\/10\/greenup-inspirer-collaborer-favoriser\/#primaryimage"},"thumbnailUrl":"https:\/\/green-up.ch\/wp-content\/uploads\/2021\/09\/3-1.png","articleSection":["G\u00e9n\u00e9ral"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/green-up.ch\/fr\/2021\/09\/10\/greenup-inspirer-collaborer-favoriser\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/green-up.ch\/fr\/2021\/09\/10\/greenup-inspirer-collaborer-favoriser\/","url":"https:\/\/green-up.ch\/fr\/2021\/09\/10\/greenup-inspirer-collaborer-favoriser\/","name":"GreenUp - inspirer, collaborer, favoriser ! | Green Up","isPartOf":{"@id":"https:\/\/green-up.ch\/#website"},"primaryImageOfPage":{"@id":"https:\/\/green-up.ch\/fr\/2021\/09\/10\/greenup-inspirer-collaborer-favoriser\/#primaryimage"},"image":{"@id":"https:\/\/green-up.ch\/fr\/2021\/09\/10\/greenup-inspirer-collaborer-favoriser\/#primaryimage"},"thumbnailUrl":"https:\/\/green-up.ch\/wp-content\/uploads\/2021\/09\/3-1.png","datePublished":"2021-09-10T07:15:44+00:00","dateModified":"2021-09-20T11:50:02+00:00","breadcrumb":{"@id":"https:\/\/green-up.ch\/fr\/2021\/09\/10\/greenup-inspirer-collaborer-favoriser\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/green-up.ch\/fr\/2021\/09\/10\/greenup-inspirer-collaborer-favoriser\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/green-up.ch\/fr\/2021\/09\/10\/greenup-inspirer-collaborer-favoriser\/#primaryimage","url":"https:\/\/green-up.ch\/wp-content\/uploads\/2021\/09\/3-1.png","contentUrl":"https:\/\/green-up.ch\/wp-content\/uploads\/2021\/09\/3-1.png","width":2048,"height":1152},{"@type":"BreadcrumbList","@id":"https:\/\/green-up.ch\/fr\/2021\/09\/10\/greenup-inspirer-collaborer-favoriser\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/green-up.ch\/"},{"@type":"ListItem","position":2,"name":"GreenUp &#8211; inspirer, collaborer, favoriser !"}]},{"@type":"WebSite","@id":"https:\/\/green-up.ch\/#website","url":"https:\/\/green-up.ch\/","name":"GreenUp","description":"Inspire, collaborate, empower.","publisher":{"@id":"https:\/\/green-up.ch\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/green-up.ch\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/green-up.ch\/#organization","name":"GreeUp","url":"https:\/\/green-up.ch\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/green-up.ch\/#\/schema\/logo\/image\/","url":"https:\/\/green-up.ch\/wp-content\/uploads\/2021\/11\/greenuplogo_rond.png","contentUrl":"https:\/\/green-up.ch\/wp-content\/uploads\/2021\/11\/greenuplogo_rond.png","width":600,"height":595,"caption":"GreeUp"},"image":{"@id":"https:\/\/green-up.ch\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/m.facebook.com\/greenupswitzerland","https:\/\/www.instagram.com\/greenup.ch\/","https:\/\/www.linkedin.com\/company\/greenupswitzerland\/"]},{"@type":"Person","@id":"https:\/\/green-up.ch\/#\/schema\/person\/96bc3613ab7b4c304aa334dc4f32ec6f","name":"Nicole","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/5557b90d41c7a6762b388c7f6d44095d114d13d304ec05f8c3142ea72c8748dc?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5557b90d41c7a6762b388c7f6d44095d114d13d304ec05f8c3142ea72c8748dc?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5557b90d41c7a6762b388c7f6d44095d114d13d304ec05f8c3142ea72c8748dc?s=96&d=mm&r=g","caption":"Nicole"},"url":"https:\/\/green-up.ch\/fr\/author\/nicole\/"}]}},"_links":{"self":[{"href":"https:\/\/green-up.ch\/fr\/wp-json\/wp\/v2\/posts\/4440","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/green-up.ch\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/green-up.ch\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/green-up.ch\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/green-up.ch\/fr\/wp-json\/wp\/v2\/comments?post=4440"}],"version-history":[{"count":2,"href":"https:\/\/green-up.ch\/fr\/wp-json\/wp\/v2\/posts\/4440\/revisions"}],"predecessor-version":[{"id":4971,"href":"https:\/\/green-up.ch\/fr\/wp-json\/wp\/v2\/posts\/4440\/revisions\/4971"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/green-up.ch\/fr\/wp-json\/wp\/v2\/media\/4880"}],"wp:attachment":[{"href":"https:\/\/green-up.ch\/fr\/wp-json\/wp\/v2\/media?parent=4440"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/green-up.ch\/fr\/wp-json\/wp\/v2\/categories?post=4440"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/green-up.ch\/fr\/wp-json\/wp\/v2\/tags?post=4440"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}