{"id":6612,"date":"2022-03-22T09:36:44","date_gmt":"2022-03-22T09:36:44","guid":{"rendered":"https:\/\/green-up.ch\/2022\/03\/22\/wieso-ist-less-more-nicht-einfach\/"},"modified":"2022-03-22T13:08:06","modified_gmt":"2022-03-22T13:08:06","slug":"wieso-ist-less-more-nicht-einfach","status":"publish","type":"post","link":"https:\/\/green-up.ch\/de\/2022\/03\/22\/wieso-ist-less-more-nicht-einfach\/","title":{"rendered":"Wieso ist \u201cless = more\u201d nicht einfach?"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8220;1&#8243; _builder_version=&#8220;3.22&#8243; min_height=&#8220;954px&#8220; custom_padding=&#8220;0px|||||&#8220;][et_pb_row _builder_version=&#8220;3.25&#8243; background_size=&#8220;initial&#8220; background_position=&#8220;top_left&#8220; background_repeat=&#8220;repeat&#8220; custom_padding=&#8220;0px||0px|||&#8220;][et_pb_column type=&#8220;4_4&#8243; _builder_version=&#8220;3.25&#8243; custom_padding=&#8220;|||&#8220; custom_padding__hover=&#8220;|||&#8220;][et_pb_text _builder_version=&#8220;4.9.10&#8243; background_size=&#8220;initial&#8220; background_position=&#8220;top_left&#8220; background_repeat=&#8220;repeat&#8220;]<\/p>\n<p>Hast du dich jemals gefragt, warum es f\u00fcr die Menschen so schwer ist, mit weniger zufriedener zu leben? Letzte Woche waren wir auf dem 18. Europ\u00e4ischen Trendtag des Gottlieb Duttweiler Instituts. Das Thema aller Vortr\u00e4ge und Pr\u00e4sentationen war &#8222;Frugale Innovation&#8220;.<\/p>\n<p>&nbsp;<\/p>\n<p>Zun\u00e4chst einmal war das, was <a href=\"https:\/\/www.jasonhickel.org\/\"><strong>Jason Hickel<\/strong><\/a> zum Thema &#8222;Entwachstum&#8220; (Degrowth) pr\u00e4sentierte, nicht neu, aber die Zahlen sind dennoch ziemlich erschreckend, wenn man sie sieht. Sie geben uns eine zus\u00e4tzliche Motivation f\u00fcr das, was wir tun. Es liegt wirklich an uns &#8211; den reichen Industriel\u00e4ndern &#8211; die Art und Weise, wie wir zusammen leben und arbeiten, zu \u00e4ndern.<\/p>\n<p>&nbsp;<\/p>\n<p>Was mich sehr fasziniert hat, war der Vortrag von <a href=\"https:\/\/www.leidyklotz.com\/\"><strong>Leidy Klotz<\/strong><\/a> und die Pr\u00e4sentation seiner Forschungsergebnisse. Er fand heraus, dass es den Menschen wirklich schwer f\u00e4llt, Dinge zu subtrahieren. Dass die Menschen dazu neigen, Dinge hinzuzuf\u00fcgen &#8230; zu ihrem Leben, zu ihrem Outfit, zu ihrem Haus, ja zu so ziemlich allem &#8230; um die Dinge besser zu machen. Daher ist die Botschaft, dass weniger mehr ist, nicht einfach zu vermitteln, und zwar nicht nur, weil es mit &#8222;Verzicht&#8220; zu tun hat, sondern weil es offenbar in unserer DNA verankert ist, dass mehr besser ist. Umso wichtiger ist unsere Mission und die Arbeit (mit anderen Partners) an L\u00f6sungen in dieser Richtung anzustreben.<\/p>\n<p>&nbsp;<\/p>\n<p>Was sind also L\u00f6sungen? Nun, wir glauben nach wie vor, dass Menschen durch Handeln lernen, und deshalb wollen wir Gelegenheiten f\u00fcr Menschen schaffen, um positive Erfahrungen mit einem einfacheren Leben zu machen.<\/p>\n<p>&nbsp;<\/p>\n<p>In wenigen Wochen startet in Basel unser &#8222;<strong><a href=\"www.gosimple.ch\">GoSimple Challenge<\/a><\/strong>&#8222;, ein Pilotprojekt, bei dem Haushalte aller Art ein sechs monatiges Programm durchlaufen werden. Die Challenge beinhaltet praktische Workshops und die Teilnehmer k\u00f6nnen sich gegenseitig bei der Bew\u00e4ltigung der verschiedenen Herausforderungen zur Vereinfachung ihres Lebens unterst\u00fctzen.<\/p>\n<p>&nbsp;<\/p>\n<p>Aber es gibt nat\u00fcrlich noch viel mehr, was wir tun k\u00f6nnen, und wir freuen uns darauf, mit vielen anderen Partnern zusammenzuarbeiten, um dies zu erreichen. Bleiben Sie dran f\u00fcr unseren n\u00e4chsten Blogbeitrag und weitere Inspirationen f\u00fcr kreative L\u00f6sungen!<\/p>\n<p>Fortsetzung folgt &#8230;<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hast du dich jemals gefragt, warum es f\u00fcr die Menschen so schwer ist, mit weniger zufriedener zu leben? Letzte Woche waren wir auf dem 18. Europ\u00e4ischen Trendtag des Gottlieb Duttweiler [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":6604,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[120],"tags":[],"class_list":["post-6612","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Wieso ist \u201cless = more\u201d nicht einfach? | GreenUp<\/title>\n<meta name=\"description\" content=\"Hast du dich jemals gefragt, warum es f\u00fcr die Menschen so schwer ist, mit weniger zufriedener zu leben? Letzte Woche waren wir auf dem 18. Europ\u00e4ischen Trendtag des Gottlieb Duttweiler Instituts. Das Thema aller Vortr\u00e4ge und Pr\u00e4sentationen war &quot;Frugale Innovation&quot;.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/green-up.ch\/de\/2022\/03\/22\/wieso-ist-less-more-nicht-einfach\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Wieso ist \u201cless = more\u201d nicht einfach? | GreenUp\" \/>\n<meta property=\"og:description\" content=\"Hast du dich jemals gefragt, warum es f\u00fcr die Menschen so schwer ist, mit weniger zufriedener zu leben? Letzte Woche waren wir auf dem 18. Europ\u00e4ischen Trendtag des Gottlieb Duttweiler Instituts. Das Thema aller Vortr\u00e4ge und Pr\u00e4sentationen war &quot;Frugale Innovation&quot;.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/green-up.ch\/de\/2022\/03\/22\/wieso-ist-less-more-nicht-einfach\/\" \/>\n<meta property=\"og:site_name\" content=\"GreenUp\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/m.facebook.com\/greenupswitzerland\" \/>\n<meta property=\"article:published_time\" content=\"2022-03-22T09:36:44+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-03-22T13:08:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/green-up.ch\/wp-content\/uploads\/2022\/03\/Screen-Shot-2022-03-20-at-21.14.33-1024x435.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"435\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Nicole\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Nicole\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/green-up.ch\\\/de\\\/2022\\\/03\\\/22\\\/wieso-ist-less-more-nicht-einfach\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/green-up.ch\\\/de\\\/2022\\\/03\\\/22\\\/wieso-ist-less-more-nicht-einfach\\\/\"},\"author\":{\"name\":\"Nicole\",\"@id\":\"https:\\\/\\\/green-up.ch\\\/#\\\/schema\\\/person\\\/96bc3613ab7b4c304aa334dc4f32ec6f\"},\"headline\":\"Wieso ist \u201cless = more\u201d nicht einfach?\",\"datePublished\":\"2022-03-22T09:36:44+00:00\",\"dateModified\":\"2022-03-22T13:08:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/green-up.ch\\\/de\\\/2022\\\/03\\\/22\\\/wieso-ist-less-more-nicht-einfach\\\/\"},\"wordCount\":427,\"commentCount\":1,\"publisher\":{\"@id\":\"https:\\\/\\\/green-up.ch\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/green-up.ch\\\/de\\\/2022\\\/03\\\/22\\\/wieso-ist-less-more-nicht-einfach\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/green-up.ch\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/Screen-Shot-2022-03-20-at-21.14.33.png\",\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/green-up.ch\\\/de\\\/2022\\\/03\\\/22\\\/wieso-ist-less-more-nicht-einfach\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/green-up.ch\\\/de\\\/2022\\\/03\\\/22\\\/wieso-ist-less-more-nicht-einfach\\\/\",\"url\":\"https:\\\/\\\/green-up.ch\\\/de\\\/2022\\\/03\\\/22\\\/wieso-ist-less-more-nicht-einfach\\\/\",\"name\":\"Wieso ist \u201cless = more\u201d nicht einfach? | GreenUp\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/green-up.ch\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/green-up.ch\\\/de\\\/2022\\\/03\\\/22\\\/wieso-ist-less-more-nicht-einfach\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/green-up.ch\\\/de\\\/2022\\\/03\\\/22\\\/wieso-ist-less-more-nicht-einfach\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/green-up.ch\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/Screen-Shot-2022-03-20-at-21.14.33.png\",\"datePublished\":\"2022-03-22T09:36:44+00:00\",\"dateModified\":\"2022-03-22T13:08:06+00:00\",\"description\":\"Hast du dich jemals gefragt, warum es f\u00fcr die Menschen so schwer ist, mit weniger zufriedener zu leben? Letzte Woche waren wir auf dem 18. Europ\u00e4ischen Trendtag des Gottlieb Duttweiler Instituts. Das Thema aller Vortr\u00e4ge und Pr\u00e4sentationen war \\\"Frugale Innovation\\\".\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/green-up.ch\\\/de\\\/2022\\\/03\\\/22\\\/wieso-ist-less-more-nicht-einfach\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/green-up.ch\\\/de\\\/2022\\\/03\\\/22\\\/wieso-ist-less-more-nicht-einfach\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/green-up.ch\\\/de\\\/2022\\\/03\\\/22\\\/wieso-ist-less-more-nicht-einfach\\\/#primaryimage\",\"url\":\"https:\\\/\\\/green-up.ch\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/Screen-Shot-2022-03-20-at-21.14.33.png\",\"contentUrl\":\"https:\\\/\\\/green-up.ch\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/Screen-Shot-2022-03-20-at-21.14.33.png\",\"width\":2852,\"height\":1212},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/green-up.ch\\\/de\\\/2022\\\/03\\\/22\\\/wieso-ist-less-more-nicht-einfach\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/green-up.ch\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Wieso ist \u201cless = more\u201d nicht einfach?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/green-up.ch\\\/#website\",\"url\":\"https:\\\/\\\/green-up.ch\\\/\",\"name\":\"GreenUp\",\"description\":\"Inspire, collaborate, empower.\",\"publisher\":{\"@id\":\"https:\\\/\\\/green-up.ch\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/green-up.ch\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/green-up.ch\\\/#organization\",\"name\":\"GreeUp\",\"url\":\"https:\\\/\\\/green-up.ch\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/green-up.ch\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/green-up.ch\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/greenuplogo_rond.png\",\"contentUrl\":\"https:\\\/\\\/green-up.ch\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/greenuplogo_rond.png\",\"width\":600,\"height\":595,\"caption\":\"GreeUp\"},\"image\":{\"@id\":\"https:\\\/\\\/green-up.ch\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/m.facebook.com\\\/greenupswitzerland\",\"https:\\\/\\\/www.instagram.com\\\/greenup.ch\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/greenupswitzerland\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/green-up.ch\\\/#\\\/schema\\\/person\\\/96bc3613ab7b4c304aa334dc4f32ec6f\",\"name\":\"Nicole\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5557b90d41c7a6762b388c7f6d44095d114d13d304ec05f8c3142ea72c8748dc?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5557b90d41c7a6762b388c7f6d44095d114d13d304ec05f8c3142ea72c8748dc?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5557b90d41c7a6762b388c7f6d44095d114d13d304ec05f8c3142ea72c8748dc?s=96&d=mm&r=g\",\"caption\":\"Nicole\"},\"url\":\"https:\\\/\\\/green-up.ch\\\/de\\\/author\\\/nicole\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Wieso ist \u201cless = more\u201d nicht einfach? | GreenUp","description":"Hast du dich jemals gefragt, warum es f\u00fcr die Menschen so schwer ist, mit weniger zufriedener zu leben? Letzte Woche waren wir auf dem 18. Europ\u00e4ischen Trendtag des Gottlieb Duttweiler Instituts. Das Thema aller Vortr\u00e4ge und Pr\u00e4sentationen war \"Frugale Innovation\".","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/green-up.ch\/de\/2022\/03\/22\/wieso-ist-less-more-nicht-einfach\/","og_locale":"de_DE","og_type":"article","og_title":"Wieso ist \u201cless = more\u201d nicht einfach? | GreenUp","og_description":"Hast du dich jemals gefragt, warum es f\u00fcr die Menschen so schwer ist, mit weniger zufriedener zu leben? Letzte Woche waren wir auf dem 18. Europ\u00e4ischen Trendtag des Gottlieb Duttweiler Instituts. Das Thema aller Vortr\u00e4ge und Pr\u00e4sentationen war \"Frugale Innovation\".","og_url":"https:\/\/green-up.ch\/de\/2022\/03\/22\/wieso-ist-less-more-nicht-einfach\/","og_site_name":"GreenUp","article_publisher":"https:\/\/m.facebook.com\/greenupswitzerland","article_published_time":"2022-03-22T09:36:44+00:00","article_modified_time":"2022-03-22T13:08:06+00:00","og_image":[{"width":1024,"height":435,"url":"https:\/\/green-up.ch\/wp-content\/uploads\/2022\/03\/Screen-Shot-2022-03-20-at-21.14.33-1024x435.png","type":"image\/png"}],"author":"Nicole","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Nicole","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/green-up.ch\/de\/2022\/03\/22\/wieso-ist-less-more-nicht-einfach\/#article","isPartOf":{"@id":"https:\/\/green-up.ch\/de\/2022\/03\/22\/wieso-ist-less-more-nicht-einfach\/"},"author":{"name":"Nicole","@id":"https:\/\/green-up.ch\/#\/schema\/person\/96bc3613ab7b4c304aa334dc4f32ec6f"},"headline":"Wieso ist \u201cless = more\u201d nicht einfach?","datePublished":"2022-03-22T09:36:44+00:00","dateModified":"2022-03-22T13:08:06+00:00","mainEntityOfPage":{"@id":"https:\/\/green-up.ch\/de\/2022\/03\/22\/wieso-ist-less-more-nicht-einfach\/"},"wordCount":427,"commentCount":1,"publisher":{"@id":"https:\/\/green-up.ch\/#organization"},"image":{"@id":"https:\/\/green-up.ch\/de\/2022\/03\/22\/wieso-ist-less-more-nicht-einfach\/#primaryimage"},"thumbnailUrl":"https:\/\/green-up.ch\/wp-content\/uploads\/2022\/03\/Screen-Shot-2022-03-20-at-21.14.33.png","inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/green-up.ch\/de\/2022\/03\/22\/wieso-ist-less-more-nicht-einfach\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/green-up.ch\/de\/2022\/03\/22\/wieso-ist-less-more-nicht-einfach\/","url":"https:\/\/green-up.ch\/de\/2022\/03\/22\/wieso-ist-less-more-nicht-einfach\/","name":"Wieso ist \u201cless = more\u201d nicht einfach? | GreenUp","isPartOf":{"@id":"https:\/\/green-up.ch\/#website"},"primaryImageOfPage":{"@id":"https:\/\/green-up.ch\/de\/2022\/03\/22\/wieso-ist-less-more-nicht-einfach\/#primaryimage"},"image":{"@id":"https:\/\/green-up.ch\/de\/2022\/03\/22\/wieso-ist-less-more-nicht-einfach\/#primaryimage"},"thumbnailUrl":"https:\/\/green-up.ch\/wp-content\/uploads\/2022\/03\/Screen-Shot-2022-03-20-at-21.14.33.png","datePublished":"2022-03-22T09:36:44+00:00","dateModified":"2022-03-22T13:08:06+00:00","description":"Hast du dich jemals gefragt, warum es f\u00fcr die Menschen so schwer ist, mit weniger zufriedener zu leben? Letzte Woche waren wir auf dem 18. Europ\u00e4ischen Trendtag des Gottlieb Duttweiler Instituts. Das Thema aller Vortr\u00e4ge und Pr\u00e4sentationen war \"Frugale Innovation\".","breadcrumb":{"@id":"https:\/\/green-up.ch\/de\/2022\/03\/22\/wieso-ist-less-more-nicht-einfach\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/green-up.ch\/de\/2022\/03\/22\/wieso-ist-less-more-nicht-einfach\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/green-up.ch\/de\/2022\/03\/22\/wieso-ist-less-more-nicht-einfach\/#primaryimage","url":"https:\/\/green-up.ch\/wp-content\/uploads\/2022\/03\/Screen-Shot-2022-03-20-at-21.14.33.png","contentUrl":"https:\/\/green-up.ch\/wp-content\/uploads\/2022\/03\/Screen-Shot-2022-03-20-at-21.14.33.png","width":2852,"height":1212},{"@type":"BreadcrumbList","@id":"https:\/\/green-up.ch\/de\/2022\/03\/22\/wieso-ist-less-more-nicht-einfach\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/green-up.ch\/"},{"@type":"ListItem","position":2,"name":"Wieso ist \u201cless = more\u201d nicht einfach?"}]},{"@type":"WebSite","@id":"https:\/\/green-up.ch\/#website","url":"https:\/\/green-up.ch\/","name":"GreenUp","description":"Inspire, collaborate, empower.","publisher":{"@id":"https:\/\/green-up.ch\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/green-up.ch\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/green-up.ch\/#organization","name":"GreeUp","url":"https:\/\/green-up.ch\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/green-up.ch\/#\/schema\/logo\/image\/","url":"https:\/\/green-up.ch\/wp-content\/uploads\/2021\/11\/greenuplogo_rond.png","contentUrl":"https:\/\/green-up.ch\/wp-content\/uploads\/2021\/11\/greenuplogo_rond.png","width":600,"height":595,"caption":"GreeUp"},"image":{"@id":"https:\/\/green-up.ch\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/m.facebook.com\/greenupswitzerland","https:\/\/www.instagram.com\/greenup.ch\/","https:\/\/www.linkedin.com\/company\/greenupswitzerland\/"]},{"@type":"Person","@id":"https:\/\/green-up.ch\/#\/schema\/person\/96bc3613ab7b4c304aa334dc4f32ec6f","name":"Nicole","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/5557b90d41c7a6762b388c7f6d44095d114d13d304ec05f8c3142ea72c8748dc?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5557b90d41c7a6762b388c7f6d44095d114d13d304ec05f8c3142ea72c8748dc?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5557b90d41c7a6762b388c7f6d44095d114d13d304ec05f8c3142ea72c8748dc?s=96&d=mm&r=g","caption":"Nicole"},"url":"https:\/\/green-up.ch\/de\/author\/nicole\/"}]}},"_links":{"self":[{"href":"https:\/\/green-up.ch\/de\/wp-json\/wp\/v2\/posts\/6612","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/green-up.ch\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/green-up.ch\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/green-up.ch\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/green-up.ch\/de\/wp-json\/wp\/v2\/comments?post=6612"}],"version-history":[{"count":3,"href":"https:\/\/green-up.ch\/de\/wp-json\/wp\/v2\/posts\/6612\/revisions"}],"predecessor-version":[{"id":6650,"href":"https:\/\/green-up.ch\/de\/wp-json\/wp\/v2\/posts\/6612\/revisions\/6650"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/green-up.ch\/de\/wp-json\/wp\/v2\/media\/6604"}],"wp:attachment":[{"href":"https:\/\/green-up.ch\/de\/wp-json\/wp\/v2\/media?parent=6612"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/green-up.ch\/de\/wp-json\/wp\/v2\/categories?post=6612"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/green-up.ch\/de\/wp-json\/wp\/v2\/tags?post=6612"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}