{"id":4285,"date":"2021-09-09T14:45:37","date_gmt":"2021-09-09T14:45:37","guid":{"rendered":"https:\/\/green-up.ch\/ressourcen\/living-building-energy\/"},"modified":"2023-03-14T19:52:53","modified_gmt":"2023-03-14T19:52:53","slug":"living-building-energy","status":"publish","type":"page","link":"https:\/\/green-up.ch\/de\/simple-living\/living-building-energy\/","title":{"rendered":"Living, Building &#038; Energy"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8220;1&#8243; admin_label=&#8220;Header&#8220; _builder_version=&#8220;4.16&#8243; custom_margin=&#8220;||-5px||false|false&#8220; custom_margin_tablet=&#8220;||0px||false|false&#8220; custom_margin_phone=&#8220;&#8220; custom_margin_last_edited=&#8220;on|desktop&#8220; custom_padding=&#8220;0px||||false|false&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_row column_structure=&#8220;3_5,2_5&#8243; _builder_version=&#8220;4.16&#8243; custom_padding=&#8220;0px||0px||false|false&#8220; border_width_left=&#8220;150px&#8220; border_color_left=&#8220;rgba(0,0,0,0)&#8220; border_width_left_tablet=&#8220;0px&#8220; border_width_left_phone=&#8220;&#8220; border_width_left_last_edited=&#8220;on|desktop&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_column type=&#8220;3_5&#8243; _builder_version=&#8220;4.16&#8243; background_color=&#8220;#E6FFEB&#8220; background_color_gradient_direction=&#8220;90deg&#8220; transform_translate_linked=&#8220;off&#8220; custom_padding=&#8220;60px|40px|||false|false&#8220; custom_padding_tablet=&#8220;40px|40px||40px|false|true&#8220; custom_padding_phone=&#8220;|20px||20px|false|true&#8220; custom_padding_last_edited=&#8220;on|phone&#8220; custom_css_main_element=&#8220;overflow:visible;&#8220; border_radii=&#8220;off|||30px|30px&#8220; box_shadow_vertical_tablet=&#8220;-200px&#8220; box_shadow_vertical_phone=&#8220;-100px&#8220; box_shadow_vertical_last_edited=&#8220;on|phone&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_text _builder_version=&#8220;4.16&#8243; header_text_color=&#8220;#000000&#8243; header_font_size=&#8220;104px&#8220; z_index=&#8220;1&#8243; custom_margin=&#8220;|||-150px||&#8220; custom_margin_tablet=&#8220;|||0px&#8220; custom_margin_phone=&#8220;&#8220; custom_margin_last_edited=&#8220;on|phone&#8220; header_font_size_tablet=&#8220;80px&#8220; header_font_size_phone=&#8220;60px&#8220; header_font_size_last_edited=&#8220;on|phone&#8220; header_letter_spacing_tablet=&#8220;0px&#8220; header_letter_spacing_phone=&#8220;&#8220; header_letter_spacing_last_edited=&#8220;on|tablet&#8220; global_colors_info=&#8220;{}&#8220;]<\/p>\n<h1><span style=\"font-weight: 400; color: #00506e;\">Wohnen, Bauen &amp; Energie<\/span><\/h1>\n<p>[\/et_pb_text][et_pb_image src=&#8220;https:\/\/green-up.ch\/wp-content\/uploads\/2021\/09\/11.png&#8220; title_text=&#8220;11&#8243; _builder_version=&#8220;4.16&#8243; transform_scale_tablet=&#8220;&#8220; transform_scale_phone=&#8220;&#8220; transform_scale_last_edited=&#8220;on|desktop&#8220; transform_translate=&#8220;120px|0px&#8220; transform_translate_tablet=&#8220;0px|0px&#8220; transform_translate_phone=&#8220;&#8220; transform_translate_last_edited=&#8220;on|tablet&#8220; transform_translate_linked=&#8220;off&#8220; transform_rotate_tablet=&#8220;&#8220; transform_rotate_phone=&#8220;&#8220; transform_rotate_last_edited=&#8220;on|desktop&#8220; transform_skew_tablet=&#8220;&#8220; transform_skew_phone=&#8220;&#8220; transform_skew_last_edited=&#8220;on|desktop&#8220; transform_origin_tablet=&#8220;&#8220; transform_origin_phone=&#8220;&#8220; transform_origin_last_edited=&#8220;on|desktop&#8220; transform_styles_last_edited=&#8220;on|tablet&#8220; width=&#8220;62%&#8220; max_width=&#8220;400px&#8220; max_width_tablet=&#8220;250px&#8220; max_width_phone=&#8220;180px&#8220; max_width_last_edited=&#8220;on|desktop&#8220; module_alignment=&#8220;right&#8220; custom_margin=&#8220;-200px||-260px||false|false&#8220; custom_margin_tablet=&#8220;-50px||-160px||false|false&#8220; custom_margin_phone=&#8220;||-110px||false|false&#8220; custom_margin_last_edited=&#8220;on|phone&#8220; transform_styles_tablet=&#8220;&#8220; transform_styles_phone=&#8220;&#8220; module_alignment_tablet=&#8220;center&#8220; module_alignment_phone=&#8220;&#8220; module_alignment_last_edited=&#8220;on|desktop&#8220; global_colors_info=&#8220;{}&#8220;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8220;2_5&#8243; _builder_version=&#8220;4.16&#8243; global_colors_info=&#8220;{}&#8220;][et_pb_text _builder_version=&#8220;4.16&#8243; text_font=&#8220;|800|||||||&#8220; text_font_size=&#8220;16px&#8220; text_line_height=&#8220;1.6em&#8220; header_2_font=&#8220;||||||||&#8220; header_4_font=&#8220;Prompt|600||on|||||&#8220; header_4_font_size=&#8220;12px&#8220; header_4_letter_spacing=&#8220;2px&#8220; header_4_line_height=&#8220;1.2em&#8220; background_color=&#8220;#00506E&#8220; z_index=&#8220;1&#8243; background_layout=&#8220;dark&#8220; custom_margin=&#8220;|-4vw|||false|false&#8220; custom_margin_tablet=&#8220;|0vw|||false|false&#8220; custom_margin_phone=&#8220;&#8220; custom_margin_last_edited=&#8220;on|tablet&#8220; custom_padding=&#8220;80px|40px|60px|40px|false|true&#8220; custom_padding_tablet=&#8220;&#8220; custom_padding_phone=&#8220;40px|20px|40px|20px|true|true&#8220; custom_padding_last_edited=&#8220;on|phone&#8220; border_radii=&#8220;off|||30px|30px&#8220; locked=&#8220;off&#8220; global_colors_info=&#8220;{}&#8220;]<\/p>\n<p><strong>&#8222;Der Versuch, gl\u00fccklich zu sein, indem man Besitzt\u00fcmer anh\u00e4uft, ist so, als w\u00fcrde man versuchen, seinen Hunger zu stillen, indem man sich Sandwiches auf den K\u00f6rper klebt.&#8220; \u2013 George Carlin<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8220;4.16&#8243; text_font=&#8220;||||||||&#8220; text_font_size=&#8220;16px&#8220; text_line_height=&#8220;1.6em&#8220; header_2_font=&#8220;Prompt|800|||||||&#8220; header_2_text_color=&#8220;#f76538&#8243; header_2_font_size=&#8220;40px&#8220; header_2_line_height=&#8220;1.2em&#8220; z_index=&#8220;1&#8243; text_orientation=&#8220;right&#8220; custom_margin=&#8220;80px||||false|false&#8220; custom_margin_tablet=&#8220;0px||||false|false&#8220; custom_margin_phone=&#8220;&#8220; custom_margin_last_edited=&#8220;on|desktop&#8220; custom_padding=&#8220;|||19px|false|false&#8220; custom_padding_tablet=&#8220;|||0px|false|false&#8220; custom_padding_phone=&#8220;&#8220; custom_padding_last_edited=&#8220;on|desktop&#8220; link_option_url_new_window=&#8220;on&#8220; header_2_font_size_tablet=&#8220;30px&#8220; header_2_font_size_phone=&#8220;20px&#8220; header_2_font_size_last_edited=&#8220;on|phone&#8220; text_text_align=&#8220;right&#8220; locked=&#8220;off&#8220; global_colors_info=&#8220;{}&#8220; text_text_align_tablet=&#8220;left&#8220; text_text_align_last_edited=&#8220;on|desktop&#8220; text_text_align_phone=&#8220;left&#8220;]<\/p>\n<p>Die Art und Weise, wie wir leben, der Raum, den wir bewohnen, und die Materialien, die wir im Haus und ausserhalb des Hauses verwenden, sind alle miteinander verbunden. Sie haben einen grossen Einfluss auf unser Gl\u00fcck und auf die Umwelt. Wie k\u00f6nnen wir also einfacher leben und Energie in unseren Geb\u00e4uden nutzen?<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8220;1&#8243; _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_row _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_column type=&#8220;4_4&#8243; _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_text _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;]<\/p>\n<h1 style=\"text-align: center;\">Weniger Raum, mehr Leben<\/h1>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8220;3_4,1_4&#8243; _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_column type=&#8220;3_4&#8243; _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_video src=&#8220;https:\/\/www.youtube.com\/watch?v=QI8SGdcnQv4&#8243; play_icon_color=&#8220;#87F5B4&#8243; _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; border_radii=&#8220;on|30px|30px|30px|30px&#8220; global_colors_info=&#8220;{}&#8220;][\/et_pb_video][\/et_pb_column][et_pb_column type=&#8220;1_4&#8243; _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_text _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; width=&#8220;100%&#8220; min_height=&#8220;503px&#8220; global_colors_info=&#8220;{}&#8220;]<\/p>\n<p>Je mehr Platz wir beanspruchen, desto mehr Ressourcen verbrauchen wir. Die durchschnittliche Wohnfl\u00e4che pro Person betr\u00e4gt in der Schweiz<strong> 46m2<\/strong>. Das ist mehr als der EU-Durchschnitt von<strong> 42,6 m2<\/strong>.\u00a0<\/p>\n<p>Immer mehr Menschen sind mit kleineren R\u00e4umen zufrieden. Cleveres Design trifft auf soziale Verantwortung, was zu weniger Abfall, niedrigeren Rechnungen und mehr Zeit f\u00fcr sch\u00f6ne Dinge f\u00fchrt.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8220;1&#8243; _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; min_height=&#8220;1287px&#8220; custom_padding=&#8220;0px|||||&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_row _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; custom_padding=&#8220;0px||2px|||&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_column type=&#8220;4_4&#8243; _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_text _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; min_height=&#8220;32px&#8220; custom_margin=&#8220;||-6px|||&#8220; global_colors_info=&#8220;{}&#8220;]<\/p>\n<h2><span style=\"color: #00506e;\">Wohnen und leben<\/span><\/h2>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_column type=&#8220;4_4&#8243; _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_text _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;]<\/p>\n<p>Es gibt nicht nur die &#8222;Tiny-House-Bewegung&#8220;; es gibt viele M\u00f6glichkeiten, mit weniger gl\u00fccklicher zu wohnen und leben. Zum Beispiel:\u00a0<\/p>\n<ul>\n<li>Hauskonzepte, die gemeinsame R\u00e4ume f\u00fcr Menschen haben: eine K\u00fcche, einen Garten oder ein Spielzimmer.\u00a0<\/li>\n<li>Minimalismus: sich von allen Dingen trennen, die man nicht wirklich braucht (oder nicht wirklich liebt, wie Marie Kondo sagt)<\/li>\n<li>Gemeinschaftliches Wohnen: Auch wenn es nicht f\u00fcr alle ist, helfen sich die Bewohner gegenseitig sehr viel. Ein mehr-Generationshaus geh\u00f6rt auch dazu. \u00a0<\/li>\n<\/ul>\n<p>Indem man R\u00e4ume effizienter nutzt, die H\u00f6he ausnutzt und haltbare Materialien verwendet, kann man auch im eigenen Haus oder in der eigenen Wohnung eine Menge tun. Auf diese Weise kannst du multifunktionale R\u00e4ume schaffen oder R\u00e4ume f\u00fcr neue Nutzungsarten freigeben. Durch ein Umdenken bei den M\u00f6beln und Ger\u00e4ten kannst du ein neues, entspanntes Gef\u00fchl schaffen, mit langlebigen Ger\u00e4ten. M\u00f6bel zum Beispiel&#8230; in den meisten F\u00e4llen halten renovierte hochwertige Sofas oder St\u00fchle l\u00e4nger als billigere M\u00f6bel, und sie sind auch zeitloser!<\/p>\n<p>[\/et_pb_text][et_pb_image src=&#8220;https:\/\/green-up.ch\/wp-content\/uploads\/2021\/09\/6-slimme-manieren-om-zelfs-een-kleine-ruimte-op-te-delen.jpg&#8220; title_text=&#8220;6-slimme-manieren-om-zelfs-een-kleine-ruimte-op-te-delen&#8220; force_fullwidth=&#8220;on&#8220; _builder_version=&#8220;4.16&#8243; max_width_tablet=&#8220;100%&#8220; max_width_phone=&#8220;&#8220; max_width_last_edited=&#8220;on|desktop&#8220; custom_margin=&#8220;30px||||false|false&#8220; border_radii=&#8220;on|30px|30px|30px|30px&#8220; locked=&#8220;off&#8220; global_colors_info=&#8220;{}&#8220;][\/et_pb_image][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; min_height=&#8220;166px&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_column type=&#8220;4_4&#8243; _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_text _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;]<\/p>\n<p>Kleineres Wohnen bedeutet in den meisten F\u00e4llen mehr Zusammenleben. Man teilt R\u00e4ume, hilft sich gegenseitig. Oder in anderen F\u00e4llen bedeutet es, dass man n\u00e4her an der Natur lebt. Auch das hat nat\u00fcrlich seine Vorteile.<\/p>\n<p>Nachfolgend einige Beispiele f\u00fcr verschiedene Wohnkonzepte, die auf dem Vormarsch sind. \u00a0Gerade auch f\u00fcr \u00e4ltere Menschen ist es interessant, mit anderen aus der gleichen oder j\u00fcngeren Generation zusammenzuleben.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8220;1&#8243; _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; custom_margin=&#8220;-79px||-59px|||&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_row _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_column type=&#8220;4_4&#8243; _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_gallery gallery_ids=&#8220;3542,3546,3567,3571&#8243; _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; background_color=&#8220;RGBA(0,0,0,0)&#8220; border_radii_image=&#8220;on|8px|8px|8px|8px&#8220; global_colors_info=&#8220;{}&#8220;][\/et_pb_gallery][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8220;1&#8243; _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; min_height=&#8220;1226px&#8220; custom_margin=&#8220;43px|||||&#8220; custom_padding=&#8220;0px|||||&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_row column_structure=&#8220;1_2,1_2&#8243; _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; custom_padding=&#8220;||49px|||&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_column type=&#8220;1_2&#8243; _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_text _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; hover_enabled=&#8220;0&#8243; global_colors_info=&#8220;{}&#8220; sticky_enabled=&#8220;0&#8243;]<\/p>\n<h2>Bauwesen und Geb\u00e4ude<\/h2>\n<p>Wenn man die M\u00f6glichkeit hat, umzuziehen, aber auch einen Teil eines Geb\u00e4udes zu bauen oder umzubauen, gibt es heutzutage viele coole nachhaltige Optionen, die auch ein gem\u00fctlicheres und einladenderes Gef\u00fchl vermitteln und nat\u00fcrlich Kosten sparen, so dass man mehr Zeit mit den Dingen verbringen kann, die man liebt.\u00a0<\/p>\n<p>Zum Beispiel Geb\u00e4ude aus Holz, oder neue, gem\u00fctlichere Projekte, wie &#8222;Kalkbreite&#8220; in Z\u00fcrich oder &#8222;Erlen&#8220; in Basel, und hier stellen wir das (Single-)Haus der Zukunft vor. \u00a0<\/p>\n<p>Langfristig bringen diese Optionen sowohl dir als auch der Umwelt eine Menge.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8220;1_2&#8243; _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_image src=&#8220;https:\/\/green-up.ch\/wp-content\/uploads\/2021\/09\/net-zero-home-of-the-future-infographic-600&#215;477-1.jpg&#8220; title_text=&#8220;net-zero-home-of-the-future-infographic-600&#215;477&#8243; force_fullwidth=&#8220;on&#8220; _builder_version=&#8220;4.16&#8243; max_width_tablet=&#8220;100%&#8220; max_width_phone=&#8220;&#8220; max_width_last_edited=&#8220;on|desktop&#8220; custom_margin=&#8220;30px||||false|false&#8220; border_radii=&#8220;on|30px|30px|30px|30px&#8220; locked=&#8220;off&#8220; global_colors_info=&#8220;{}&#8220;][\/et_pb_image][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8220;1_2,1_2&#8243; _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_column type=&#8220;1_2&#8243; _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_text _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; custom_padding=&#8220;||0px|||&#8220; global_colors_info=&#8220;{}&#8220;]<\/p>\n<p><strong>Was kann ich als Mieter (auch) tun?<\/strong><\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; custom_padding=&#8220;||0px|||&#8220; global_colors_info=&#8220;{}&#8220;]<\/p>\n<p>Hier siehst du, wie viel und wo Energie in deinem Haus verbraucht wird.\u00a0<\/p>\n<p>[\/et_pb_text][et_pb_image src=&#8220;https:\/\/green-up.ch\/wp-content\/uploads\/2021\/09\/0137-lbs.jpg&#8220; title_text=&#8220;0137-lbs&#8220; force_fullwidth=&#8220;on&#8220; _builder_version=&#8220;4.16&#8243; max_width_tablet=&#8220;100%&#8220; max_width_phone=&#8220;&#8220; max_width_last_edited=&#8220;on|desktop&#8220; custom_margin=&#8220;30px||||false|false&#8220; border_radii=&#8220;on|30px|30px|30px|30px&#8220; locked=&#8220;off&#8220; global_colors_info=&#8220;{}&#8220;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8220;1_2&#8243; _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_text _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; custom_padding=&#8220;||0px|||&#8220; global_colors_info=&#8220;{}&#8220;]<\/p>\n<p><span style=\"font-weight: 400;\"><\/span><\/p>\n<p><span style=\"font-weight: 400;\"><\/span><\/p>\n<p><span style=\"font-weight: 400;\"><\/span><\/p>\n<ul>\n<li>Repariere und verwende hochwertige Gegenst\u00e4nde wie Smartphones und Computer, anstatt sie zu ersetzen, da ihre Herstellung sehr ressourcenintensiv und ihre Entsorgung schwierig ist.<\/li>\n<li>Erw\u00e4ge den Austausch alter Haushaltsger\u00e4te, wenn das neue (und energieeffizientere) Ger\u00e4t sehr h\u00e4ufig benutzt wird. Beispiele sind ineffiziente Gefrierger\u00e4te, Klimaanlagen, Waschmaschinen, Beleuchtungs- und Heizungssysteme.<\/li>\n<li>Verfasse einen Brief an deinen Vermieter, in dem du den Einbau eines umweltfreundlichen Heizsystems vorschl\u00e4gst. Du kannst auch verlangen, dass die Heizkosten individuell auf der Grundlage deines pers\u00f6nlichen Energieverbrauchs abgerechnet werden, anstatt die Standardheizkosten zu zahlen, die normalerweise pro Quadratmeter berechnet werden.<\/li>\n<li>Wenn man die Heizung um 1 Grad herunterdreht, spart man 2-3% Energie. Ein Schlafzimmer mit einer Temperatur von 16-18 Grad ist optimal.<\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\">Verzichte auf deinen Trockner und wasche bei niedrigen Temperaturen. Das Aufh\u00e4ngen der W\u00e4sche nimmt vielleicht 10 Minuten in Anspruch, aber wie viele andere Hausarbeiten aktiviert es dich und macht dich hinterher zufriedener.<\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">W\u00e4hle deinen Energieversorger und deine Produkte mit Bedacht, denn es gibt viele umweltfreundliche Optionen.<\/span><span style=\"font-weight: 400;\"><\/span><\/li>\n<\/ul>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; custom_padding=&#8220;0px|||||&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_column type=&#8220;4_4&#8243; _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_text _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; custom_padding=&#8220;||0px|||&#8220; global_colors_info=&#8220;{}&#8220;]<\/p>\n<p>Viele dieser Massnahmen helfen dir, auf einfache Art und Weise Energie und damit Ressourcen sowie Geld zu sparen, so dass du z.B. weniger arbeiten musst.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Wohnen, Bauen &amp; Energie&#8220;Der Versuch, gl\u00fccklich zu sein, indem man Besitzt\u00fcmer anh\u00e4uft, ist so, als w\u00fcrde man versuchen, seinen Hunger zu stillen, indem man sich Sandwiches auf den K\u00f6rper klebt.&#8220; [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":4233,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"class_list":["post-4285","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Living, Building &amp; Energy | GreenUp<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/green-up.ch\/simple-living\/living-building-energy\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Living, Building &amp; Energy | GreenUp\" \/>\n<meta property=\"og:description\" content=\"Wohnen, Bauen &amp; Energie&quot;Der Versuch, gl\u00fccklich zu sein, indem man Besitzt\u00fcmer anh\u00e4uft, ist so, als w\u00fcrde man versuchen, seinen Hunger zu stillen, indem man sich Sandwiches auf den K\u00f6rper klebt.&quot; [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/green-up.ch\/simple-living\/living-building-energy\/\" \/>\n<meta property=\"og:site_name\" content=\"GreenUp\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/m.facebook.com\/greenupswitzerland\" \/>\n<meta property=\"article:modified_time\" content=\"2023-03-14T19:52:53+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"11\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/green-up.ch\\\/simple-living\\\/living-building-energy\\\/\",\"url\":\"https:\\\/\\\/green-up.ch\\\/simple-living\\\/living-building-energy\\\/\",\"name\":\"Living, Building & Energy | GreenUp\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/green-up.ch\\\/#website\"},\"datePublished\":\"2021-09-09T14:45:37+00:00\",\"dateModified\":\"2023-03-14T19:52:53+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/green-up.ch\\\/simple-living\\\/living-building-energy\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/green-up.ch\\\/simple-living\\\/living-building-energy\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/green-up.ch\\\/simple-living\\\/living-building-energy\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/green-up.ch\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Das Einfache Leben\",\"item\":\"https:\\\/\\\/green-up.ch\\\/simple-living\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Living, Building &#038; Energy\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/green-up.ch\\\/#website\",\"url\":\"https:\\\/\\\/green-up.ch\\\/\",\"name\":\"GreenUp\",\"description\":\"Inspire, collaborate, empower.\",\"publisher\":{\"@id\":\"https:\\\/\\\/green-up.ch\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/green-up.ch\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/green-up.ch\\\/#organization\",\"name\":\"GreeUp\",\"url\":\"https:\\\/\\\/green-up.ch\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/green-up.ch\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/green-up.ch\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/greenuplogo_rond.png\",\"contentUrl\":\"https:\\\/\\\/green-up.ch\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/greenuplogo_rond.png\",\"width\":600,\"height\":595,\"caption\":\"GreeUp\"},\"image\":{\"@id\":\"https:\\\/\\\/green-up.ch\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/m.facebook.com\\\/greenupswitzerland\",\"https:\\\/\\\/www.instagram.com\\\/greenup.ch\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/greenupswitzerland\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Living, Building & Energy | GreenUp","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/green-up.ch\/simple-living\/living-building-energy\/","og_locale":"de_DE","og_type":"article","og_title":"Living, Building & Energy | GreenUp","og_description":"Wohnen, Bauen &amp; Energie\"Der Versuch, gl\u00fccklich zu sein, indem man Besitzt\u00fcmer anh\u00e4uft, ist so, als w\u00fcrde man versuchen, seinen Hunger zu stillen, indem man sich Sandwiches auf den K\u00f6rper klebt.\" [&hellip;]","og_url":"https:\/\/green-up.ch\/simple-living\/living-building-energy\/","og_site_name":"GreenUp","article_publisher":"https:\/\/m.facebook.com\/greenupswitzerland","article_modified_time":"2023-03-14T19:52:53+00:00","twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"11\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/green-up.ch\/simple-living\/living-building-energy\/","url":"https:\/\/green-up.ch\/simple-living\/living-building-energy\/","name":"Living, Building & Energy | GreenUp","isPartOf":{"@id":"https:\/\/green-up.ch\/#website"},"datePublished":"2021-09-09T14:45:37+00:00","dateModified":"2023-03-14T19:52:53+00:00","breadcrumb":{"@id":"https:\/\/green-up.ch\/simple-living\/living-building-energy\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/green-up.ch\/simple-living\/living-building-energy\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/green-up.ch\/simple-living\/living-building-energy\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/green-up.ch\/"},{"@type":"ListItem","position":2,"name":"Das Einfache Leben","item":"https:\/\/green-up.ch\/simple-living\/"},{"@type":"ListItem","position":3,"name":"Living, Building &#038; Energy"}]},{"@type":"WebSite","@id":"https:\/\/green-up.ch\/#website","url":"https:\/\/green-up.ch\/","name":"GreenUp","description":"Inspire, collaborate, empower.","publisher":{"@id":"https:\/\/green-up.ch\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/green-up.ch\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/green-up.ch\/#organization","name":"GreeUp","url":"https:\/\/green-up.ch\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/green-up.ch\/#\/schema\/logo\/image\/","url":"https:\/\/green-up.ch\/wp-content\/uploads\/2021\/11\/greenuplogo_rond.png","contentUrl":"https:\/\/green-up.ch\/wp-content\/uploads\/2021\/11\/greenuplogo_rond.png","width":600,"height":595,"caption":"GreeUp"},"image":{"@id":"https:\/\/green-up.ch\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/m.facebook.com\/greenupswitzerland","https:\/\/www.instagram.com\/greenup.ch\/","https:\/\/www.linkedin.com\/company\/greenupswitzerland\/"]}]}},"_links":{"self":[{"href":"https:\/\/green-up.ch\/de\/wp-json\/wp\/v2\/pages\/4285","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/green-up.ch\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/green-up.ch\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/green-up.ch\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/green-up.ch\/de\/wp-json\/wp\/v2\/comments?post=4285"}],"version-history":[{"count":7,"href":"https:\/\/green-up.ch\/de\/wp-json\/wp\/v2\/pages\/4285\/revisions"}],"predecessor-version":[{"id":11326,"href":"https:\/\/green-up.ch\/de\/wp-json\/wp\/v2\/pages\/4285\/revisions\/11326"}],"up":[{"embeddable":true,"href":"https:\/\/green-up.ch\/de\/wp-json\/wp\/v2\/pages\/4233"}],"wp:attachment":[{"href":"https:\/\/green-up.ch\/de\/wp-json\/wp\/v2\/media?parent=4285"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}